{"id":3341,"date":"2024-02-22T13:53:05","date_gmt":"2024-02-22T13:53:05","guid":{"rendered":"https:\/\/abenteueroase.vcp-bbb.de\/?p=3341"},"modified":"2024-07-09T14:58:39","modified_gmt":"2024-07-09T14:58:39","slug":"save-the-date","status":"publish","type":"post","link":"https:\/\/abenteueroase.vcp-bbb.de\/en\/save-the-date","title":{"rendered":"SAVE THE DATE"},"content":{"rendered":"<p>Die Sommerferien kommen bestimmt und in den ersten 3 Wochen machen wir Programm! Die \u00d6ffnungszeiten sind dann von 10:00 Uhr bis 15:00 Uhr und wir sind alle 5 Wochentage f\u00fcr euch da!<\/p>\n\n\n\n<p>Speichert euch schonmal das Datum, denn ihr wollt sicher dabei sein, wenn wir wieder Kisten klettern und Pizza backen!<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Sommerferien kommen bestimmt und in den ersten 3 Wochen machen wir Programm! Die \u00d6ffnungszeiten sind dann von 10:00 Uhr bis 15:00 Uhr und wir sind alle 5 Wochentage f\u00fcr euch da! Speichert euch schonmal das Datum, denn ihr wollt sicher dabei sein, wenn wir wieder Kisten klettern und Pizza backen!<\/p>","protected":false},"author":3,"featured_media":3371,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[52,56,54],"class_list":["post-3341","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veranstaltungen","tag-abo","tag-ferien","tag-ferienprogramm"],"_links":{"self":[{"href":"https:\/\/abenteueroase.vcp-bbb.de\/en\/wp-json\/wp\/v2\/posts\/3341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/abenteueroase.vcp-bbb.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/abenteueroase.vcp-bbb.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/abenteueroase.vcp-bbb.de\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/abenteueroase.vcp-bbb.de\/en\/wp-json\/wp\/v2\/comments?post=3341"}],"version-history":[{"count":3,"href":"https:\/\/abenteueroase.vcp-bbb.de\/en\/wp-json\/wp\/v2\/posts\/3341\/revisions"}],"predecessor-version":[{"id":3358,"href":"https:\/\/abenteueroase.vcp-bbb.de\/en\/wp-json\/wp\/v2\/posts\/3341\/revisions\/3358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/abenteueroase.vcp-bbb.de\/en\/wp-json\/wp\/v2\/media\/3371"}],"wp:attachment":[{"href":"https:\/\/abenteueroase.vcp-bbb.de\/en\/wp-json\/wp\/v2\/media?parent=3341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/abenteueroase.vcp-bbb.de\/en\/wp-json\/wp\/v2\/categories?post=3341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/abenteueroase.vcp-bbb.de\/en\/wp-json\/wp\/v2\/tags?post=3341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}